{"id":12287,"date":"2020-04-21T08:51:59","date_gmt":"2020-04-21T06:51:59","guid":{"rendered":"https:\/\/www.chg.at\/?p=12287"},"modified":"2020-04-24T14:37:50","modified_gmt":"2020-04-24T12:37:50","slug":"gast-rohregger-mueller-sport-covid-19","status":"publish","type":"post","link":"https:\/\/www.chg.at\/en\/gast-rohregger-mueller-sport-covid-19\/","title":{"rendered":"Informationen zu Sport und Covid-19"},"content":{"rendered":"<style type=\"text\/css\"> \n#cmsmasters_row_6a050e93881a01_21591886 .cmsmasters_row_outer_parent { \n\tpadding-top: 0px; \n} \n\n#cmsmasters_row_6a050e93881a01_21591886 .cmsmasters_row_outer_parent { \n\tpadding-bottom: 0px; \n} \n\n \n#cmsmasters_row_6a050e93884454_45213090 .cmsmasters_row_outer_parent { \n\tpadding-top: 0px; \n} \n\n#cmsmasters_row_6a050e93884454_45213090 .cmsmasters_row_outer_parent { \n\tpadding-bottom: 40px; \n} \n\n \n#cmsmasters_divider_6a050e938853a4_95099465 { \n\tborder-bottom-width:1px; \n\tborder-bottom-style:dotted; \n\tpadding-top:10px; \n\tmargin-bottom:20px; \n\tborder-bottom-color:#aaaaaa;\n} \n\n#cmsmasters_button_6a050e93885f23_82178188 { \n\ttext-align:center; \n} \n\n#cmsmasters_button_6a050e93885f23_82178188 .cmsmasters_button:before { \n\tmargin-right:.5em; \n\tmargin-left:0; \n\tvertical-align:baseline; \n} \n\n#cmsmasters_button_6a050e93885f23_82178188 .cmsmasters_button { \n\tfont-weight:normal; \n\tfont-style:normal; \n\tborder-style:solid; \n} \n#cmsmasters_button_6a050e93885f23_82178188 .cmsmasters_button:hover { \n} \n \n#cmsmasters_divider_6a050e93886755_01498446 { \n\tborder-bottom-width:1px; \n\tborder-bottom-style:dotted; \n\tpadding-top:10px; \n\tmargin-bottom:20px; \n\tborder-bottom-color:#aaaaaa;\n} \n\n#cmsmasters_button_6a050e93887273_00063438 { \n\ttext-align:center; \n} \n\n#cmsmasters_button_6a050e93887273_00063438 .cmsmasters_button:before { \n\tmargin-right:.5em; \n\tmargin-left:0; \n\tvertical-align:baseline; \n} \n\n#cmsmasters_button_6a050e93887273_00063438 .cmsmasters_button { \n\tfont-weight:normal; \n\tfont-style:normal; \n\tborder-style:solid; \n} \n#cmsmasters_button_6a050e93887273_00063438 .cmsmasters_button:hover { \n} \n \n#cmsmasters_divider_6a050e93887f91_59221400 { \n\tborder-bottom-width:1px; \n\tborder-bottom-style:dotted; \n\tpadding-top:10px; \n\tmargin-bottom:20px; \n\tborder-bottom-color:#aaaaaa;\n} \n\n#cmsmasters_button_6a050e9388f871_25483555 { \n\ttext-align:center; \n} \n\n#cmsmasters_button_6a050e9388f871_25483555 .cmsmasters_button:before { \n\tmargin-right:.5em; \n\tmargin-left:0; \n\tvertical-align:baseline; \n} \n\n#cmsmasters_button_6a050e9388f871_25483555 .cmsmasters_button { \n\tfont-weight:normal; \n\tfont-style:normal; \n\tborder-style:solid; \n} \n#cmsmasters_button_6a050e9388f871_25483555 .cmsmasters_button:hover { \n} \n \n#cmsmasters_row_6a050e9388fda3_39933272 .cmsmasters_row_outer_parent { \n\tpadding-top: 0px; \n} \n\n#cmsmasters_row_6a050e9388fda3_39933272 .cmsmasters_row_outer_parent { \n\tpadding-bottom: 40px; \n} \n\n \n#cmsmasters_divider_6a050e938908f7_77428029 { \n\tborder-bottom-width:1px; \n\tborder-bottom-style:dotted; \n\tpadding-top:10px; \n\tmargin-bottom:20px; \n\tborder-bottom-color:#aaaaaa;\n} \n\n#cmsmasters_button_6a050e938965a7_62176387 { \n\ttext-align:center; \n} \n\n#cmsmasters_button_6a050e938965a7_62176387 .cmsmasters_button:before { \n\tmargin-right:.5em; \n\tmargin-left:0; \n\tvertical-align:baseline; \n} \n\n#cmsmasters_button_6a050e938965a7_62176387 .cmsmasters_button { \n\tfont-weight:normal; \n\tfont-style:normal; \n\tborder-style:solid; \n} \n#cmsmasters_button_6a050e938965a7_62176387 .cmsmasters_button:hover { \n} \n \n#cmsmasters_divider_6a050e93897448_67576790 { \n\tborder-bottom-width:1px; \n\tborder-bottom-style:dotted; \n\tpadding-top:10px; \n\tmargin-bottom:20px; \n\tborder-bottom-color:#aaaaaa;\n} \n\n#cmsmasters_button_6a050e9389d3a5_81450180 { \n\ttext-align:center; \n} \n\n#cmsmasters_button_6a050e9389d3a5_81450180 .cmsmasters_button:before { \n\tmargin-right:.5em; \n\tmargin-left:0; \n\tvertical-align:baseline; \n} \n\n#cmsmasters_button_6a050e9389d3a5_81450180 .cmsmasters_button { \n\tfont-weight:normal; \n\tfont-style:normal; \n\tborder-style:solid; \n} \n#cmsmasters_button_6a050e9389d3a5_81450180 .cmsmasters_button:hover { \n} \n<\/style><div id=\"cmsmasters_row_6a050e93881a01_21591886\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div class=\"cmsmasters_column one_first\">\n<div class=\"cmsmasters_text\">\n<div class=\"innerContent\">\n<h1 style=\"text-align: left;\"><strong><span style=\"color: #d43555;\">Sport und Covid-19<\/span><\/strong><\/h1>\n<h1 style=\"text-align: left;\"><strong><span style=\"color: #d43555;\">Allgemeine Fragen und Antworten<\/span><\/strong><\/h1>\n<p><em>Von RA Dr. G\u00fcnther Gast, RA Mag. Florian M\u00fcller und RAA Mag. Thomas Rohregger<br \/>\n<\/em><\/p>\n<p>Die Corona-Krise sorgt in \u00d6sterreich f\u00fcr gro\u00dfe Unsicherheit bei Sportlern, Vereinen, Berufssportlern und Veranstaltern. G\u00fcnther Gast, Florian M\u00fcller und Thomas Rohregger von CHG Rechtsanw\u00e4lte beantworten brennende Fragen zu den rechtlichen Auswirkungen der Covid-19-Pandemie auf die Sportwelt.<\/p>\n<h3><strong>Darf derzeit in \u00d6sterreich Sport ausge\u00fcbt werden?<\/strong><\/h3>\n<p>Die Verordnung des Bundesministers f\u00fcr Soziales, Gesundheit, Pflege und Konsumentenschutz gem\u00e4\u00df \u00a7 2 Z 1 des COVID-19-Ma\u00dfnahmengesetzes, verbietet das Betreten \u00f6ffentlicher Orte bis zumindest 30.4, wobei eine Verl\u00e4ngerung dieser Verordnung von der Bundesregierung bereits angek\u00fcndigt wurde. Fraglich ist f\u00fcr viele, inwieweit dies nun die Sportaus\u00fcbung derzeit betrifft.<\/p>\n<p>Nach \u00a7 5 der Ma\u00dfnahmenverordnung des Bundes ist jedenfalls die Sportaus\u00fcbung auf Sportpl\u00e4tzen ausdr\u00fccklich verboten. Zudem darf jegliche sportliche Bet\u00e4tigung, welche an sich nicht im Freien befindlichen \u00f6ffentlichen Pl\u00e4tzen stattfindet, nicht ausge\u00fcbt werden. Bei jeder anderen Sportaus\u00fcbung ist auf zweierlei Dinge zu achten. Zum einen sollte <u>alleine<\/u> gesportelt werden. Eine Ausnahme besteht f\u00fcr Personen, die im gemeinsamen Haushalt leben. Zu beachten ist hierbei, dass zu anderen Personen der <u>Mindestabstand von einem Meter eingehalten<\/u> werden muss. Zweitens muss im Falle einer Kontrolle durch Sicherheitsorgane glaubhaft gemacht werden, weshalb die Aus\u00fcbung des Sportes im Einzelfall zul\u00e4ssig ist.<\/p>\n<p>Hinzuzuf\u00fcgen ist, dass die Verordnung eine genaue Regelung der Sportaus\u00fcbung, bzw die Bestrafung derer, in der Krisenzeit offen l\u00e4sst, weshalb auf den Zweck der Norm zu achten ist. Dieser liegt darin, Ressourcen (besonders im medizinischen Bereich) zu sparen und die Ausbreitung des Coronavirus zu stoppen. Jegliche Sportaus\u00fcbung, die dessen entgegenwirkt, ist unserer Auffassung nach verboten. Insbesondere denken wir hierbei an Sportarten, die f\u00fcr die aus\u00fcbende Person ein erh\u00f6htes Risiko (wie einer Verletzung) mit sich bringt. Auch hier werden die Beh\u00f6rden im Einzelfall entscheiden.<\/p>\n<p>Vergangene Woche wurde seitens des Sportministeriums angek\u00fcndigt, dass mit 1. Mai 2020 vereinzelte Sportanlagen vom Verbot des \u00a75 Ma\u00dfnahmenverordnung ausgenommen werden. Der genaue Inhalt der Verordnung wird derzeit noch ausgearbeitet, doch wurde vom zust\u00e4ndigen Minister bereits mitgeteilt, dass etwa das Golfspielen, Tennisspielen, diverse Leichtathletik-Sportarten, der Pferdesport und der Flugsport ab Anfang Mai auf den jeweiligen Sportanalgen unter Einhaltung konkreter Auflagen ausge\u00fcbt werden d\u00fcrfen. Vorl\u00e4ufig werden auch Umkleidekabinen, Gemeinschaftsr\u00e4ume und Duschen geschlossen bleiben m\u00fcssen. Die jeweiligen Fachverb\u00e4nde sind dazu angehalten, sportartenspezifische Richtlinien zu erarbeiten, um die\u00a0 Einhaltung der Hygieneregeln sicherzustellen. Diese m\u00fcssen \u00a0vor dem erstmaligen Betreten der jeweiligen Sportanlage von den Sportaus\u00fcbenden zur Kenntnis genommen \u00a0werden.<\/p>\n<p>Grunds\u00e4tzlich darf mit einer \u00d6ffnung jener Sportanlagen gerechnet werden, welche nach Art und Weise des Sports, den <u>Abstand zwischen den Sportlern von mindestens 2 Metern, <\/u>sowie die allgemeinen Hygieneregeln gew\u00e4hrleisten. Daher ist mit einer \u00d6ffnung von beispielsweise Fu\u00dfball-, Basketball- oder Beachvolleyballpl\u00e4tzen noch nicht zu rechnen. Indoor-Sportpl\u00e4tze werden jedenfalls nicht \u00f6ffnen.<\/p>\n<h3><strong>Was gilt f\u00fcr Berufssportler?<\/strong><\/h3>\n<p>Zur Ausgangssperre besteht wie gesagt die Ausnahme zur Aus\u00fcbung beruflicher T\u00e4tigkeiten. Allerdings ist auch das Training von Berufssportlern an die Ausgangssperre anzupassen, weil das Verlassen des eigenen Wohnsitzes auf ein zeitlich und \u00f6rtlich unbedingt notwendiges Minimum zu beschr\u00e4nken ist.<\/p>\n<p>Seit dem 20.04.2020 sind Spitzensportler von dem Betretungsverbot f\u00fcr Sportst\u00e4tten ausgenommen . Das bedeutet, dass Berufssportler mit dem genannten Tag ihr Training wieder aufnehmen durften. F\u00fcr die jeweiligen Sportarten sind jedoch Sonderregeln f\u00fcr den Trainingsablauf zu beachten. So muss f\u00fcr Indoor-Spitzensportler ein isolierter Mindestbewegungsbereich von 20m\u00b2 in der Sportanlage \u00a0sichergestellt sein. Das Training von Profi-Sportmannschaften darf ausschlie\u00dflich in Kleingruppen stattfinden.<\/p>\n<p>Als Spitzensportler gelten jene Personen, die ihre sportliche T\u00e4tigkeit beruflich aus\u00fcben, Eink\u00fcnfte daraus erzielen (z.B. auch F\u00f6rdergelder, Sporthilfe, Sportpool, Sponsorgelder, Preisgelder) und an international hochklassigen Wettk\u00e4mpfen teilnehmen.<\/p>\n<p>Zudem sind die jeweiligen Trainer und Betreuer (damit sind auch Physiobetreuer oder \u00c4rzte gemeint) zur Betreuung des Spitzensportlers vom Betretungsverbot ausgenommen.<\/p>\n<p><strong>Im unten angef\u00fchrten Link finden Sie den gesamten Artikel mit weiteren Fragen und Antworten<em>.<\/em> Zudem finden Sie zu diesem Thema einige mediale Beitr\u00e4ge von unseren CHG Juristen<\/strong><strong>.<\/strong><\/p>\n<p><em>Diese Ausf\u00fchrungen stellen einen \u00dcberblick dar und k\u00f6nnen die Beratung im Einzelfall nicht ersetzen, da sich die Situation laufend \u00e4ndert. F\u00fcr Detailfragen steht Ihnen unser Team der CHG-Rechtsanw\u00e4lte gerne zur Verf\u00fcgung<\/em><em>.<\/em><\/p>\n<p><a href=\"http:\/\/chg.at\/profile\/arnold-autengruber\">D<\/a><a href=\"http:\/\/chg.at\/profile\/guenther-gast\">Dr. G\u00fcnther Gast<\/a> und <a href=\"https:\/\/www.chg.at\/profile\/florian-mueller\/\">Mag. Florian M\u00fcller<\/a> sind Partner, <a href=\"https:\/\/www.chg.at\/profile\/thomas-rohregger\/\">Mag. Thomas Rohregger <\/a>ist Rechtsanwaltsanw\u00e4rter bei CHG Czernich Rechtsanw\u00e4lte.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_6a050e93884454_45213090\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div class=\"cmsmasters_column one_half\">\n\n<div id=\"cmsmasters_divider_6a050e938853a4_95099465\" class=\"cmsmasters_divider cmsmasters_divider_width_long cmsmasters_divider_pos_left\"><\/div><div class=\"cmsmasters_text\">\n<p>\u00a0<\/p>\n<\/div>\n\n<div id=\"cmsmasters_button_6a050e93885f23_82178188\" class=\"button_wrap\"><a href=\"https:\/\/www.chg.at\/wp-content\/uploads\/2020\/04\/Sport-und-Covid-19.pdf\" class=\"ripple cmsmasters_button\"><span>Zum Text als PDF<\/span><\/a><\/div>\n<div class=\"cmsmasters_text\">\n<p>\u00a0<\/p>\n<\/div>\n\n<div id=\"cmsmasters_divider_6a050e93886755_01498446\" class=\"cmsmasters_divider cmsmasters_divider_width_long cmsmasters_divider_pos_left\"><\/div><div class=\"cmsmasters_text\">\n<p>Artikel der Tiroler Tageszeitung vom 27.03.2020<\/p>\n<\/div>\n\n<div id=\"cmsmasters_button_6a050e93887273_00063438\" class=\"button_wrap\"><a href=\"https:\/\/www.chg.at\/wp-content\/uploads\/2020\/03\/2020-03-27_Innsbruck_Seite_31.pdf\" class=\"ripple cmsmasters_button\"><span>Zum Artikel<\/span><\/a><\/div>\n<\/div>\n<div class=\"cmsmasters_column one_half\">\n\n<div id=\"cmsmasters_divider_6a050e93887f91_59221400\" class=\"cmsmasters_divider cmsmasters_divider_width_long cmsmasters_divider_pos_left\"><\/div><div class=\"aligncenter\">\n<div class=\"cmsmasters_img  cmsmasters_image_c with_caption\">\n<img src=\"https:\/\/www.chg.at\/wp-content\/uploads\/2016\/01\/CHG-Rechtsanwaelte-Guenther-Gast-thumbnail-300x300.jpg\" \/>\n<p class=\"cmsmasters_img_caption\">Dr. G\u00fcnther Gast, LL.M.<\/p><\/div>\n<\/div>\n<div class=\"cmsmasters_text\">\n<p>\u00a0<\/p>\n<\/div>\n\n<div id=\"cmsmasters_button_6a050e9388f871_25483555\" class=\"button_wrap\"><a href=\"http:\/\/www.chg.at\/profile\/guenther-gast\/\" class=\"ripple cmsmasters_button\" data-animation=\"fadeInUp\" data-delay=\"0\"><span>Zum Profil<\/span><\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_6a050e9388fda3_39933272\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div class=\"cmsmasters_column one_half\">\n\n<div id=\"cmsmasters_divider_6a050e938908f7_77428029\" class=\"cmsmasters_divider cmsmasters_divider_width_long cmsmasters_divider_pos_left\"><\/div><div class=\"cmsmasters_img  cmsmasters_image_n with_caption\">\n<img src=\"https:\/\/www.chg.at\/wp-content\/uploads\/2016\/01\/CHG-Rechtsanwaelte-Florian-Mueller-thumbnail-300x300.jpg\" \/>\n<p class=\"cmsmasters_img_caption\">Mag. Florian M\u00fcller<\/p><\/div>\n<div class=\"cmsmasters_text\">\n<p>\u00a0<\/p>\n<\/div>\n\n<div id=\"cmsmasters_button_6a050e938965a7_62176387\" class=\"button_wrap\"><a href=\"https:\/\/www.chg.at\/profile\/florian-mueller\/\" class=\"ripple cmsmasters_button\" data-animation=\"fadeInUp\" data-delay=\"0\"><span>Zum Profil<\/span><\/a><\/div>\n<\/div>\n<div class=\"cmsmasters_column one_half\">\n\n<div id=\"cmsmasters_divider_6a050e93897448_67576790\" class=\"cmsmasters_divider cmsmasters_divider_width_long cmsmasters_divider_pos_left\"><\/div><div class=\"cmsmasters_img  cmsmasters_image_n with_caption\">\n<img src=\"https:\/\/www.chg.at\/wp-content\/uploads\/2016\/01\/CHG-Rechtsanwaelte-Thomas-Rohregger-thumbnail-300x300.jpg\" \/>\n<p class=\"cmsmasters_img_caption\">Mag. Thomas Rohregger<\/p><\/div>\n<div class=\"cmsmasters_text\">\n<p>\u00a0<\/p>\n<\/div>\n\n<div id=\"cmsmasters_button_6a050e9389d3a5_81450180\" class=\"button_wrap\"><a href=\"https:\/\/www.chg.at\/profile\/thomas-rohregger\/\" class=\"ripple cmsmasters_button\" data-animation=\"fadeInUp\" data-delay=\"0\"><span>Zum Profil<\/span><\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Von CHG-Juristen Dr. G\u00fcnther Gast, Mag. Florian M\u00fcller und Mag. Thomas Rohregger<\/p>\n","protected":false},"author":10,"featured_media":12341,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"inline_featured_image":false},"categories":[6,8,60,61,68],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sport und Coronavirus - Was ist erlaubt? Fragen und Antworten<\/title>\n<meta name=\"description\" content=\"Fragen und Antworten zu Sportlern, Vereinen, Berufssportlern und Veranstaltern im Lichte der Corona Pandemie. G\u00fcnther Gast. Florian M\u00fcller. Thomas Rohregger. CHG Rechtsanw\u00e4lte.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.chg.at\/en\/gast-rohregger-mueller-sport-covid-19\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CHG\" \/>\n<meta property=\"og:description\" content=\"CHG\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.chg.at\/en\/gast-rohregger-mueller-sport-covid-19\/\" \/>\n<meta property=\"og:site_name\" content=\"CHG Czernich Rechtsanw\u00e4lte \u2013 Wir bewegen Wirtschaft\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-21T06:51:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-24T12:37:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.chg.at\/wp-content\/uploads\/2020\/04\/Recht-und-Corona.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"580\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Lorenz Held\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lorenz Held\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.chg.at\/en\/gast-rohregger-mueller-sport-covid-19\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.chg.at\/en\/gast-rohregger-mueller-sport-covid-19\/\"},\"author\":{\"name\":\"Lorenz Held\",\"@id\":\"https:\/\/www.chg.at\/en\/#\/schema\/person\/767a36d24c2ac329c1c5e1c10929e2b6\"},\"headline\":\"Informationen zu Sport und Covid-19\",\"datePublished\":\"2020-04-21T06:51:59+00:00\",\"dateModified\":\"2020-04-24T12:37:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.chg.at\/en\/gast-rohregger-mueller-sport-covid-19\/\"},\"wordCount\":1236,\"publisher\":{\"@id\":\"https:\/\/www.chg.at\/en\/#organization\"},\"articleSection\":[\"Business Tipps\",\"CHG News\",\"Medienberichterstattung\",\"Publikation\",\"Recht und Corona\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.chg.at\/en\/gast-rohregger-mueller-sport-covid-19\/\",\"url\":\"https:\/\/www.chg.at\/en\/gast-rohregger-mueller-sport-covid-19\/\",\"name\":\"Sport und Coronavirus - Was ist erlaubt? Fragen und Antworten\",\"isPartOf\":{\"@id\":\"https:\/\/www.chg.at\/en\/#website\"},\"datePublished\":\"2020-04-21T06:51:59+00:00\",\"dateModified\":\"2020-04-24T12:37:50+00:00\",\"description\":\"Fragen und Antworten zu Sportlern, Vereinen, Berufssportlern und Veranstaltern im Lichte der Corona Pandemie. G\u00fcnther Gast. Florian M\u00fcller. Thomas Rohregger. CHG Rechtsanw\u00e4lte.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.chg.at\/en\/gast-rohregger-mueller-sport-covid-19\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.chg.at\/en\/gast-rohregger-mueller-sport-covid-19\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.chg.at\/en\/gast-rohregger-mueller-sport-covid-19\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.chg.at\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Informationen zu Sport und Covid-19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.chg.at\/en\/#website\",\"url\":\"https:\/\/www.chg.at\/en\/\",\"name\":\"CHG Czernich Rechtsanw\u00e4lte \u2013 Wir bewegen Wirtschaft\",\"description\":\"Wir sorgen f\u00fcr Klarheit, wenn es rechtlich kompliziert wird. In jeder Phase Ihrer Unternehmungen. Sie ergreifen die Chancen. Wir verwandeln Risiken in L\u00f6sungen.\",\"publisher\":{\"@id\":\"https:\/\/www.chg.at\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.chg.at\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.chg.at\/en\/#organization\",\"name\":\"CHG Czernich Rechtsanw\u00e4lte\",\"url\":\"https:\/\/www.chg.at\/en\/\",\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/12773263\/admin\/dashboard\/\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.chg.at\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.chg.at\/wp-content\/uploads\/2016\/08\/CHG_logo_250_1.png\",\"contentUrl\":\"https:\/\/www.chg.at\/wp-content\/uploads\/2016\/08\/CHG_logo_250_1.png\",\"width\":250,\"height\":33,\"caption\":\"CHG Czernich Rechtsanw\u00e4lte\"},\"image\":{\"@id\":\"https:\/\/www.chg.at\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.chg.at\/en\/#\/schema\/person\/767a36d24c2ac329c1c5e1c10929e2b6\",\"name\":\"Lorenz Held\",\"sameAs\":[\"https:\/\/www.chg.at\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sport und Coronavirus - Was ist erlaubt? Fragen und Antworten","description":"Fragen und Antworten zu Sportlern, Vereinen, Berufssportlern und Veranstaltern im Lichte der Corona Pandemie. G\u00fcnther Gast. Florian M\u00fcller. Thomas Rohregger. CHG Rechtsanw\u00e4lte.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.chg.at\/en\/gast-rohregger-mueller-sport-covid-19\/","og_locale":"en_US","og_type":"article","og_title":"CHG","og_description":"CHG","og_url":"https:\/\/www.chg.at\/en\/gast-rohregger-mueller-sport-covid-19\/","og_site_name":"CHG Czernich Rechtsanw\u00e4lte \u2013 Wir bewegen Wirtschaft","article_published_time":"2020-04-21T06:51:59+00:00","article_modified_time":"2020-04-24T12:37:50+00:00","og_image":[{"width":1160,"height":580,"url":"https:\/\/www.chg.at\/wp-content\/uploads\/2020\/04\/Recht-und-Corona.png","type":"image\/png"}],"author":"Lorenz Held","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Lorenz Held","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.chg.at\/en\/gast-rohregger-mueller-sport-covid-19\/#article","isPartOf":{"@id":"https:\/\/www.chg.at\/en\/gast-rohregger-mueller-sport-covid-19\/"},"author":{"name":"Lorenz Held","@id":"https:\/\/www.chg.at\/en\/#\/schema\/person\/767a36d24c2ac329c1c5e1c10929e2b6"},"headline":"Informationen zu Sport und Covid-19","datePublished":"2020-04-21T06:51:59+00:00","dateModified":"2020-04-24T12:37:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.chg.at\/en\/gast-rohregger-mueller-sport-covid-19\/"},"wordCount":1236,"publisher":{"@id":"https:\/\/www.chg.at\/en\/#organization"},"articleSection":["Business Tipps","CHG News","Medienberichterstattung","Publikation","Recht und Corona"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.chg.at\/en\/gast-rohregger-mueller-sport-covid-19\/","url":"https:\/\/www.chg.at\/en\/gast-rohregger-mueller-sport-covid-19\/","name":"Sport und Coronavirus - Was ist erlaubt? Fragen und Antworten","isPartOf":{"@id":"https:\/\/www.chg.at\/en\/#website"},"datePublished":"2020-04-21T06:51:59+00:00","dateModified":"2020-04-24T12:37:50+00:00","description":"Fragen und Antworten zu Sportlern, Vereinen, Berufssportlern und Veranstaltern im Lichte der Corona Pandemie. G\u00fcnther Gast. Florian M\u00fcller. Thomas Rohregger. CHG Rechtsanw\u00e4lte.","breadcrumb":{"@id":"https:\/\/www.chg.at\/en\/gast-rohregger-mueller-sport-covid-19\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.chg.at\/en\/gast-rohregger-mueller-sport-covid-19\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.chg.at\/en\/gast-rohregger-mueller-sport-covid-19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.chg.at\/en\/"},{"@type":"ListItem","position":2,"name":"Informationen zu Sport und Covid-19"}]},{"@type":"WebSite","@id":"https:\/\/www.chg.at\/en\/#website","url":"https:\/\/www.chg.at\/en\/","name":"CHG Czernich Rechtsanw\u00e4lte \u2013 Wir bewegen Wirtschaft","description":"Wir sorgen f\u00fcr Klarheit, wenn es rechtlich kompliziert wird. In jeder Phase Ihrer Unternehmungen. Sie ergreifen die Chancen. Wir verwandeln Risiken in L\u00f6sungen.","publisher":{"@id":"https:\/\/www.chg.at\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.chg.at\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.chg.at\/en\/#organization","name":"CHG Czernich Rechtsanw\u00e4lte","url":"https:\/\/www.chg.at\/en\/","sameAs":["https:\/\/www.linkedin.com\/company\/12773263\/admin\/dashboard\/"],"logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.chg.at\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.chg.at\/wp-content\/uploads\/2016\/08\/CHG_logo_250_1.png","contentUrl":"https:\/\/www.chg.at\/wp-content\/uploads\/2016\/08\/CHG_logo_250_1.png","width":250,"height":33,"caption":"CHG Czernich Rechtsanw\u00e4lte"},"image":{"@id":"https:\/\/www.chg.at\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.chg.at\/en\/#\/schema\/person\/767a36d24c2ac329c1c5e1c10929e2b6","name":"Lorenz Held","sameAs":["https:\/\/www.chg.at"]}]}},"_links":{"self":[{"href":"https:\/\/www.chg.at\/en\/wp-json\/wp\/v2\/posts\/12287"}],"collection":[{"href":"https:\/\/www.chg.at\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.chg.at\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.chg.at\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chg.at\/en\/wp-json\/wp\/v2\/comments?post=12287"}],"version-history":[{"count":10,"href":"https:\/\/www.chg.at\/en\/wp-json\/wp\/v2\/posts\/12287\/revisions"}],"predecessor-version":[{"id":12382,"href":"https:\/\/www.chg.at\/en\/wp-json\/wp\/v2\/posts\/12287\/revisions\/12382"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.chg.at\/en\/wp-json\/wp\/v2\/media\/12341"}],"wp:attachment":[{"href":"https:\/\/www.chg.at\/en\/wp-json\/wp\/v2\/media?parent=12287"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.chg.at\/en\/wp-json\/wp\/v2\/categories?post=12287"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.chg.at\/en\/wp-json\/wp\/v2\/tags?post=12287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}