{"id":12324,"date":"2020-04-15T10:37:22","date_gmt":"2020-04-15T08:37:22","guid":{"rendered":"https:\/\/www.chg.at\/?p=12324"},"modified":"2020-05-20T15:23:21","modified_gmt":"2020-05-20T13:23:21","slug":"arbeitsrechtliche-covid-19-massnahmen-home-office","status":"publish","type":"post","link":"https:\/\/www.chg.at\/en\/arbeitsrechtliche-covid-19-massnahmen-home-office\/","title":{"rendered":"Arbeitsrechtliche COVID-19-Ma\u00dfnahmen: Home-Office"},"content":{"rendered":"<style type=\"text\/css\"> \n#cmsmasters_row_6a050e9ed36285_69118451 .cmsmasters_row_outer_parent { \n\tpadding-top: 0px; \n} \n\n#cmsmasters_row_6a050e9ed36285_69118451 .cmsmasters_row_outer_parent { \n\tpadding-bottom: 0px; \n} \n\n \n#cmsmasters_row_6a050e9ed3a2d3_42050234 .cmsmasters_row_outer_parent { \n\tpadding-top: 0px; \n} \n\n#cmsmasters_row_6a050e9ed3a2d3_42050234 .cmsmasters_row_outer_parent { \n\tpadding-bottom: 40px; \n} \n\n \n#cmsmasters_divider_6a050e9ed3b379_01515810 { \n\tborder-bottom-width:1px; \n\tborder-bottom-style:dotted; \n\tpadding-top:10px; \n\tmargin-bottom:20px; \n\tborder-bottom-color:#aaaaaa;\n} \n\n#cmsmasters_button_6a050e9ed3bce9_37958954 { \n\ttext-align:center; \n} \n\n#cmsmasters_button_6a050e9ed3bce9_37958954 .cmsmasters_button:before { \n\tmargin-right:.5em; \n\tmargin-left:0; \n\tvertical-align:baseline; \n} \n\n#cmsmasters_button_6a050e9ed3bce9_37958954 .cmsmasters_button { \n\tfont-weight:normal; \n\tfont-style:normal; \n\tborder-style:solid; \n} \n#cmsmasters_button_6a050e9ed3bce9_37958954 .cmsmasters_button:hover { \n} \n \n#cmsmasters_divider_6a050e9ed3c832_84073158 { \n\tborder-bottom-width:1px; \n\tborder-bottom-style:dotted; \n\tpadding-top:10px; \n\tmargin-bottom:20px; \n\tborder-bottom-color:#aaaaaa;\n} \n\n#cmsmasters_button_6a050e9ed44bd6_38376805 { \n\ttext-align:center; \n} \n\n#cmsmasters_button_6a050e9ed44bd6_38376805 .cmsmasters_button:before { \n\tmargin-right:.5em; \n\tmargin-left:0; \n\tvertical-align:baseline; \n} \n\n#cmsmasters_button_6a050e9ed44bd6_38376805 .cmsmasters_button { \n\tfont-weight:normal; \n\tfont-style:normal; \n\tborder-style:solid; \n} \n#cmsmasters_button_6a050e9ed44bd6_38376805 .cmsmasters_button:hover { \n} \n \n#cmsmasters_row_6a050e9ed450a3_43035948 .cmsmasters_row_outer_parent { \n\tpadding-top: 0px; \n} \n\n#cmsmasters_row_6a050e9ed450a3_43035948 .cmsmasters_row_outer_parent { \n\tpadding-bottom: 40px; \n} \n\n \n#cmsmasters_divider_6a050e9ed45d49_61056049 { \n\tborder-bottom-width:1px; \n\tborder-bottom-style:dotted; \n\tpadding-top:10px; \n\tmargin-bottom:20px; \n\tborder-bottom-color:#aaaaaa;\n} \n<\/style><div id=\"cmsmasters_row_6a050e9ed36285_69118451\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div class=\"cmsmasters_column one_first\">\n<div class=\"cmsmasters_text\">\n<div class=\"innerContent\">\n<h1><span style=\"color: #d43555;\"><strong><span lang=\"DE\">Arbeitsrechtliche COVID-19-Ma\u00dfnahmen: Home-Office \u2013 Regelungsbedarf und F\u00f6rderungsm\u00f6glichkeiten <\/span><\/strong><\/span><\/h1>\n<p><em>Von RAin Dr. <a href=\"https:\/\/www.chg.at\/profile\/marlene-wachter\/\">Marlene Wachter<\/a> und RAA Mag. Julia Barenth<br \/>\n<\/em><\/p>\n<p>Nicht nur w\u00e4hrend der Notwendigkeit, die Verbreitung des SARS-CoV2-Virus einzud\u00e4mmen, sondern auch im regul\u00e4ren Betrieb ist die Arbeit von zu Hause aus (auch als \u201e<em>Home-Office<\/em>\u201c oder \u201e<em>Telearbeit<\/em>\u201c benannt) eine gute M\u00f6glichkeit, den Mitarbeitereinsatz zu optimieren und gleichzeitig auch anderen Interessen und Anforderungen Rechnung zu tragen.<\/p>\n<p>Home-Office ist gesetzlich nicht geregelt. Gerade deshalb empfehlen wir dringend, die Rahmenbedingungen vorab zu kl\u00e4ren, um Missverst\u00e4ndnissen und Streitigkeiten vorzubeugen. Eine klare vertragliche Regelung kann auch Nachforderungen aus Anlass von GPLA-Pr\u00fcfungen vorbeugen.<\/p>\n<h2>I.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Allgemeines zur Vereinbarung von Home-Office<\/h2>\n<p>Es gibt in \u00d6sterreich <strong>kein Recht<\/strong> auf Home-Office. Dies hat sich auch durch die gesetzlichen und verordneten Ma\u00dfnahmen der Bundesregierung im Zusammenhang mit dem Covid-19-Ma\u00dfnahmenpaket nicht ge\u00e4ndert. Weder aus dem EpidemieG noch dem COVID-19-Ma\u00dfnahmenG l\u00e4sst sich eine Verpflichtung zur Erbringung unselbst\u00e4ndiger Arbeit von zu Hause aus ableiten. Eine kurzfristig kundgemachte \u201eHome-Office-Verordnung\u201c ist nie in Kraft getreten. Allerdings besteht aktuell eine dringende Empfehlung zur Arbeit von zu Hause aus, sofern dies m\u00f6glich ist.<\/p>\n<p>Die Erbringung von Arbeitsleistungen durch den Arbeitnehmer (AN) von zu Hause aus muss zwischen Arbeitgeber (AG) und AN <strong>vereinbart<\/strong> werden. Im Kern stellt dies eine Vereinbarung der AN-Wohnung als Arbeitsort dar. Diese Vereinbarung kann bereits in den bestehenden Arbeitsvertr\u00e4gen getroffen worden oder aufgrund der nunmehrigen Corona-Auswirkungen veranlasst sein.<\/p>\n<p>Die in Arbeitsvertr\u00e4gen h\u00e4ufig enthaltene Klausel, dass der AG den Arbeitsort ver\u00e4ndern kann, wird manchmal, aber nicht immer, eine ausreichende Grundlage sein, den AN zum Arbeiten von seiner Wohnung aus zu verpflichten.<\/p>\n<h2>II.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Anwendung des AZG<\/h2>\n<p>Nicht \u00fcbersehen werden darf, dass auch auf die Besch\u00e4ftigung des AN in seiner eigenen Wohnung das <strong>Arbeitszeitgesetz (<\/strong><strong>AZG)<\/strong> mit seinem vollen und uneingeschr\u00e4nkten Inhalt anzuwenden ist. Auch die Zeit, in der ein AN in seiner Wohnung besch\u00e4ftigt wird, ist Arbeitszeit. Folglich muss auch im Home-Office die <strong>Lage der Normalarbeitszeit<\/strong> zwischen AG und AN geregelt werden. Dies kann erfolgen durch Vereinbarung<\/p>\n<ul>\n<li>einer fixen Arbeitszeiteinteilung,<\/li>\n<li>einer durchrechenbaren Arbeitszeit oder auch<\/li>\n<li>gleitender Arbeitszeit.<\/li>\n<\/ul>\n<p>Weiterhin m\u00fcssen <strong>Arbeitszeitaufzeichnungen<\/strong> gef\u00fchrt werden. Hierbei gibt es f\u00fcr Home-Office-AN aber bestimmte Erleichterungen (\u00a7 26 Abs 3 AZG):<\/p>\n<p>F\u00fcr AN, die sowohl Telearbeit als auch Arbeit am Standort des Betriebes leisten, dabei aber nicht \u00fcberwiegend in ihrer Wohnung t\u00e4tig sind, sind die Aufzeichnungen \u00fcber den Beginn und das Ende der jeweiligen Arbeitszeit und Pausen zu f\u00fchren. Dies betrifft auch jene Arbeitszeiten, die in der Wohnung erbracht werden.<\/p>\n<p>F\u00fcr jene AN, die ihre T\u00e4tigkeit \u00fcberwiegend (mehr als 50% der Summe der Arbeitszeit, nicht Tage) in ihrer Wohnung aus\u00fcben, sind ausschlie\u00dflich Aufzeichnungen \u00fcber die Dauer der Tagesarbeitszeit zu f\u00fchren.<\/p>\n<p>Die Verpflichtung des AG zu \u00fcberpr\u00fcfen, ob die Arbeitszeit gesetzeskonform geleistet wurde, besteht unver\u00e4ndert.<\/p>\n<h2>III.\u00a0\u00a0\u00a0\u00a0\u00a0 Mit welchen Arbeitsmaterialen arbeitet der AN?<\/h2>\n<p>Grunds\u00e4tzlich sehen die gesetzlichen Bestimmungen vor, dass Materialien des Arbeitsgebrauches grunds\u00e4tzlich \u2013 abweichende Vereinbarungen m\u00f6glich \u2013 <strong>vom AG <\/strong>zur Verf\u00fcgung zu stellen oder die Kosten f\u00fcr diese von ihm zu tragen sind.<\/p>\n<p>Verwendet der <strong>AN<\/strong> <strong>eigene Betriebsmittel<\/strong> (Telefon, Internet etc.) im Interesse seines AG, hat er Anspruch auf <strong>Aufwandersatz<\/strong>. Diese Bestimmung ist allerdings ebenfalls dispositiv, dies bedeutet, dass hievon abweichende Vereinbarungen getroffen werden k\u00f6nnen. Grenze der abweichenden Vereinbarung wird die F\u00fcrsorgepflicht des AG sein und darf das Unternehmerrisiko nicht auf den AN \u00fcberw\u00e4lzt werden. Es muss sichergestellt sein,<\/p>\n<ul>\n<li>dass der vom AN zu tragende Aufwand nicht dazu f\u00fchrt, dass damit das kollektivvertragliche Mindestgehalt unterschritten wird;<\/li>\n<li>dass das Grundgehalt \u00a7 2g AVRAG weiterhin ausgewiesen ist.<\/li>\n<\/ul>\n<p>Die Kosten sonstiger Betriebsmittel, die nicht mit der Arbeit eng in Verbindung stehen und ohnehin im Haushalt des AN vorhanden sind (bspw. Tisch, Sessel), werden vom AN getragen.<\/p>\n<p><strong>Hinweis<\/strong>: Stellt der AG dem AN die technische Ausstattung f\u00fcr die Erbringung der Arbeitsleistung zur Verf\u00fcgung (z.B. Laptop, Software), kann der AG die private Nutzung dieser Betriebsmittel untersagen.<\/p>\n<h2>IV.\u00a0\u00a0\u00a0\u00a0\u00a0 Hinweise zu Haftungsfragen<\/h2>\n<p>Die <strong>Haftung f\u00fcr Betriebsmittel und Rechtsg\u00fcter<\/strong> des AG und des AN richtet sich nach den geltenden Schadentragungsregeln in Dienstverh\u00e4ltnissen iSd Dienstnehmerhaftpflichtgesetzes (DNHG). Eine Haftung des Arbeitgebers kann sich auch aus \u00a7\u00a7 67, 68 ASchG (Bestimmungen zu Bildschirmarbeitspl\u00e4tzen) ergeben.<\/p>\n<p><strong>Verunfallt der Arbeitnehmer<\/strong> im Home-Office, stellt sich die Frage, ob dies als Arbeits- oder Freizeit-Unfall zu qualifizieren ist. Davon h\u00e4ngt unter anderem die Dauer des Entgeltfortzahlungsanspruches ab.<\/p>\n<p>Ein Arbeitsunfall liegt demnach vor, wenn sich der Unfall in einem \u201e<em>wesentlich betrieblichen Zwecken dienenden Teil des Geb\u00e4udes<\/em>&#8221; ereignet, der \u201e<em>nicht mehr zu den ausschlie\u00dflich dem pers\u00f6nlichen Lebensbereich<\/em>&#8221; des AN zuzurechnenden Teilen der Wohnung geh\u00f6rt. Der OGH hatte einen Vorfall als Arbeitsunfall qualifiziert, bei dem sich ein AN auf dem R\u00fcckweg von der Toilette auf einer Holztreppe verletzte, die \u00fcberwiegend dazu ben\u00fctzt wurde, den Arbeitsplatz im Homeoffice zu erreichen (OGH 10 ObS 79\/07a).<\/p>\n<h2>V.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Empfohlene Regelungsinhalte einer Home-Office-Vereinbarung<\/h2>\n<p>Da mit der Erbringung der Arbeitsleistung im Home-Office <strong>M\u00f6glichkeiten<\/strong>, aber auch <strong>Risiken<\/strong> verbunden sind, empfiehlt es sich, in der zwischen AG und AN abzuschlie\u00dfenden Vereinbarung unter anderem nachstehende Punkte zu regeln:<\/p>\n<ul>\n<li>Festlegung der Normalarbeitszeit;<\/li>\n<li>Arbeitszeiten\/ Zeiten der Erreichbarkeit des AN (zB in Form einer Kernzeitregelung);<\/li>\n<li>Definition des Arbeitsortes: Wir empfehlen nicht nur den Wohnort des AN, sondern auch weiterhin den urspr\u00fcnglichen Arbeitsort als Ort der Leistungserbringung zu vereinbaren (wenn f\u00fcr eine gewisse Dauer nur der Wohnort des AN als Arbeitsort definiert wird und er in den Betrieb gerufen wird, k\u00f6nnte diese Reisezeit Dienstzeit und somit entgeltpflichtig werden);<\/li>\n<li>Pr\u00fcfung der Arbeitszeitaufzeichnungen und Vereinbarung, dass der AN diese unterfertigt und die Richtigkeit seiner Angaben best\u00e4tigt;<\/li>\n<li>Hinweis auf datenschutzrechtliche Bestimmungen und betriebsinterne Richtlinien sowie Vereinbarungen zum Geheimnisschutz;<\/li>\n<li>Regelungen bez\u00fcglich allf\u00e4lligen Kostenersatzes bzw. Bereitstellung von Arbeitsmitteln;<\/li>\n<li>Beendigungsm\u00f6glichkeiten des Home-Office.<\/li>\n<\/ul>\n<h2>VI.\u00a0\u00a0\u00a0\u00a0\u00a0 F\u00f6rderungen<\/h2>\n<p>K\u00fcrzlich wurde vom Land Tirol bekannt gegeben, dass Home-Office-Arbeitspl\u00e4tze finanziell gef\u00f6rdert werden. Ziel der gegenst\u00e4ndlichen Ma\u00dfnahme ist, kleine und mittlere Tiroler Unternehmen (KMU) dahingehend zu unterst\u00fctzen, Homeoffice-Arbeitspl\u00e4tze einzurichten, um eine professionelle Kommunikation zu schaffen und damit gleichzeitig einen Beitrag zur Aufrechterhaltung der Produktivit\u00e4t und Sicherung der Arbeitspl\u00e4tze zu leisten.<\/p>\n<p>M\u00f6gliche <strong>F\u00f6rderungsnehmer<\/strong> sind:<\/p>\n<p>erwerbswirtschaftliche Betreiber von touristisch bzw. freizeitwirtschaftlich relevanten Infrastruktureinrichtungen (z.B. B\u00e4der, Campingpl\u00e4tze, Bootsvermietung, Minigolfpl\u00e4tze, Freizeitparks, Kinos, Tanzschulen, Tennis und Tischtennispl\u00e4tze inkl. Tennishallen, Ballonfahr- und H\u00e4nge- bzw. Gleitschirmunternehmen, Raftingunternehmen etc.)<\/p>\n<ul>\n<li>Telekommunikations- und Rundfunkunternehmen mit der Berechtigung der RTR GmbH<\/li>\n<li>Sprengmittelh\u00e4ndler<\/li>\n<li>Buchhalter\/Bilanzbuchhalter\/Personalverrechner<\/li>\n<li>Mitglieder der Kammer der Steuerberater und Wirtschaftspr\u00fcfer mit Standort in Tirol<\/li>\n<li>Mitglieder der Kammer der Architekten und Ingenieurskonsulenten f\u00fcr Tirol und Vorarlberg mit Standort in Tirol<\/li>\n<\/ul>\n<p>Die F\u00f6rderung besteht in einem <strong>nicht r\u00fcckzahlpflichtigen Einmalzuschuss<\/strong>, wobei nachstehende <strong>Kosten<\/strong> f\u00f6rderbar sind:<\/p>\n<p>Beratungsleistungen zur Konzeption sowie zur hard- und softwarem\u00e4\u00dfigen Ausstattung des Homeoffice-Arbeitsplatzes im Ausma\u00df von max. 50%;<\/p>\n<p>Anschaffung von Software zur IT-technischen Einrichtung des Homeoffice-Arbeitsplatzes im Ausma\u00df von max. 50%;<\/p>\n<p>Anschaffung von damit in Verbindung stehender zu installierender IT-Hardware im Ausma\u00df von max. 30%, wobei der nicht r\u00fcckzahlpflichtige Einmalzuschuss pro Laptop, Desktop oder Tablet max. EUR\u00a0300,00 betr\u00e4gt.<\/p>\n<p><strong>Achtung<\/strong>: Die ausschlie\u00dfliche Anschaffung von IT-Hardware ohne Investition in Software zur IT-technischen Einrichtung des Homeoffice-Arbeitsplatzes, vom Provider verrechnete Kosten zur Einrichtung und zum Betrieb des Internetzugangs sowie die Ausstattung des Home-Office-Arbeitsplatzes mit Objektm\u00f6beln (Schreibtische etc.) sind <strong>nicht f\u00f6rderbar<\/strong>.<\/p>\n<p>Grunds\u00e4tzlich muss die Summe der f\u00f6rderbaren Kosten mindestens EUR\u00a0500,00 betragen und ist die F\u00f6rderungsbemessungsgrundlage mit EUR\u00a05.000,00 begrenzt.<\/p>\n<p>Der <strong>F\u00f6rderantrag<\/strong> ist elektronisch mit einem daf\u00fcr vorgesehenen Webformular (grunds\u00e4tzlich vor Beginn des F\u00f6rderprojektes, Ausnahmen bestehen f\u00fcr den Zeitraum 11. M\u00e4rz 2020 bis 30. April 2020) zu stellen.<\/p>\n<p>N\u00e4here Informationen finden Sie auf der Homepage des Landes Tirol unter <a href=\"https:\/\/www.tirol.gv.at\/arbeit-wirtschaft\/wirtschaftsfoerderung\/wirtschaftsfoerderungsprogramm\/homeoffice-arbeitsplaetze\/\">https:\/\/www.tirol.gv.at\/arbeit-wirtschaft\/wirtschaftsfoerderung\/wirtschaftsfoerderungsprogramm\/homeoffice-arbeitsplaetze\/<\/a><\/p>\n<p><strong><em>Disclaimer:<\/em><\/strong><em> Dieser Beitrag beinhaltet nur allgemeine Informationen und ersetzt keine Rechtsberatung. CHG Rechtsanw\u00e4lte &amp; Partner GmbH \u00fcbernimmt keinerlei Haftung f\u00fcr Inhalt und Richtigkeit dieses Beitrags. <\/em><\/p>\n<\/div>\n<div class=\"innerContent\" style=\"text-align: left;\"><\/div>\n<div class=\"innerContent\" style=\"text-align: left;\">Dr. Marlene Wachter ist Partnerin, Mag. Julia Barenth ist Rechtsanwaltsanw\u00e4rterin bei CHG Czernich Rechtsanw\u00e4lte.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_6a050e9ed3a2d3_42050234\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div class=\"cmsmasters_column one_half\">\n\n<div id=\"cmsmasters_divider_6a050e9ed3b379_01515810\" class=\"cmsmasters_divider cmsmasters_divider_width_long cmsmasters_divider_pos_left\"><\/div>\n<div id=\"cmsmasters_button_6a050e9ed3bce9_37958954\" class=\"button_wrap\"><a href=\"https:\/\/www.chg.at\/wp-content\/uploads\/2020\/04\/Arbeitsrechtliche-COVID-19-Ma\u00dfnahmen-Home-Office_CHG_Rechtsanw\u00e4lte_Wachter_Barenth.pdf\" class=\"ripple cmsmasters_button\"><span>Zum Text als PDF<\/span><\/a><\/div>\n<\/div>\n<div class=\"cmsmasters_column one_half\">\n\n<div id=\"cmsmasters_divider_6a050e9ed3c832_84073158\" class=\"cmsmasters_divider cmsmasters_divider_width_long cmsmasters_divider_pos_left\"><\/div><div class=\"cmsmasters_img  cmsmasters_image_n with_caption\">\n<img src=\"https:\/\/www.chg.at\/wp-content\/uploads\/2016\/01\/CHG-Rechtsanwaelte-Marlene-Wachter-thumbnail-300x300.jpg\" \/>\n<p class=\"cmsmasters_img_caption\">Dr. Marlene Wachter<\/p><\/div>\n<div class=\"cmsmasters_text\">\n<\/div>\n\n<div id=\"cmsmasters_button_6a050e9ed44bd6_38376805\" class=\"button_wrap\"><a href=\"https:\/\/www.chg.at\/profile\/marlene-wachter\/\" class=\"ripple cmsmasters_button\" data-animation=\"fadeInUp\" data-delay=\"0\"><span>Zum Profil<\/span><\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"cmsmasters_row_6a050e9ed450a3_43035948\" class=\"cmsmasters_row cmsmasters_color_scheme_default cmsmasters_row_top_default cmsmasters_row_bot_default cmsmasters_row_boxed\">\n<div class=\"cmsmasters_row_outer_parent\">\n<div class=\"cmsmasters_row_outer\">\n<div class=\"cmsmasters_row_inner\">\n<div class=\"cmsmasters_row_margin\">\n<div class=\"cmsmasters_column one_half\">\n\n<div id=\"cmsmasters_divider_6a050e9ed45d49_61056049\" class=\"cmsmasters_divider cmsmasters_divider_width_long cmsmasters_divider_pos_left\"><\/div><div class=\"cmsmasters_img  cmsmasters_image_n with_caption\">\n<img src=\"https:\/\/www.chg.at\/wp-content\/uploads\/2016\/01\/CHG-Rechtsanwaelte-Julia-Barenth-thumbnail-300x300.jpg\" \/>\n<p class=\"cmsmasters_img_caption\">Mag. Julia Barenth <\/p><\/div>\n<div class=\"cmsmasters_text\">\n<p>\u00a0<\/p>\n<\/div>\n<\/div>\n<div class=\"cmsmasters_column one_half\">\n<div class=\"cmsmasters_text\">\n<p>\u00a0<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Von CHG-Juristen Dr. Marlene Wachter und Mag. Julia Barenth <\/p>\n","protected":false},"author":10,"featured_media":12341,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"inline_featured_image":false},"categories":[6,8,61,68],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Covid-19 und Arbeitsrecht Home-Office \u2013 Regelungsbedarf und F\u00f6rderungsm\u00f6glichkeiten<\/title>\n<meta name=\"description\" content=\"Arbeitsrechtliche COVID-19-Ma\u00dfnahmen: Home-Office \u2013 Regelungsbedarf und F\u00f6rderungsm\u00f6glichkeiten. RA Dr. Marlene Wachter, RAA Mag. Julia Barenth. 14.04.2020.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.chg.at\/en\/arbeitsrechtliche-covid-19-massnahmen-home-office\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CHG\" \/>\n<meta property=\"og:description\" content=\"CHG\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.chg.at\/en\/arbeitsrechtliche-covid-19-massnahmen-home-office\/\" \/>\n<meta property=\"og:site_name\" content=\"CHG Czernich Rechtsanw\u00e4lte \u2013 Wir bewegen Wirtschaft\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-15T08:37:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-20T13:23:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.chg.at\/wp-content\/uploads\/2020\/04\/Recht-und-Corona.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"580\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Lorenz Held\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lorenz Held\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.chg.at\/en\/arbeitsrechtliche-covid-19-massnahmen-home-office\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.chg.at\/en\/arbeitsrechtliche-covid-19-massnahmen-home-office\/\"},\"author\":{\"name\":\"Lorenz Held\",\"@id\":\"https:\/\/www.chg.at\/en\/#\/schema\/person\/767a36d24c2ac329c1c5e1c10929e2b6\"},\"headline\":\"Arbeitsrechtliche COVID-19-Ma\u00dfnahmen: Home-Office\",\"datePublished\":\"2020-04-15T08:37:22+00:00\",\"dateModified\":\"2020-05-20T13:23:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.chg.at\/en\/arbeitsrechtliche-covid-19-massnahmen-home-office\/\"},\"wordCount\":1636,\"publisher\":{\"@id\":\"https:\/\/www.chg.at\/en\/#organization\"},\"articleSection\":[\"Business Tipps\",\"CHG News\",\"Publikation\",\"Recht und Corona\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.chg.at\/en\/arbeitsrechtliche-covid-19-massnahmen-home-office\/\",\"url\":\"https:\/\/www.chg.at\/en\/arbeitsrechtliche-covid-19-massnahmen-home-office\/\",\"name\":\"Covid-19 und Arbeitsrecht Home-Office \u2013 Regelungsbedarf und F\u00f6rderungsm\u00f6glichkeiten\",\"isPartOf\":{\"@id\":\"https:\/\/www.chg.at\/en\/#website\"},\"datePublished\":\"2020-04-15T08:37:22+00:00\",\"dateModified\":\"2020-05-20T13:23:21+00:00\",\"description\":\"Arbeitsrechtliche COVID-19-Ma\u00dfnahmen: Home-Office \u2013 Regelungsbedarf und F\u00f6rderungsm\u00f6glichkeiten. RA Dr. Marlene Wachter, RAA Mag. Julia Barenth. 14.04.2020.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.chg.at\/en\/arbeitsrechtliche-covid-19-massnahmen-home-office\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.chg.at\/en\/arbeitsrechtliche-covid-19-massnahmen-home-office\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.chg.at\/en\/arbeitsrechtliche-covid-19-massnahmen-home-office\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.chg.at\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arbeitsrechtliche COVID-19-Ma\u00dfnahmen: Home-Office\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.chg.at\/en\/#website\",\"url\":\"https:\/\/www.chg.at\/en\/\",\"name\":\"CHG Czernich Rechtsanw\u00e4lte \u2013 Wir bewegen Wirtschaft\",\"description\":\"Wir sorgen f\u00fcr Klarheit, wenn es rechtlich kompliziert wird. In jeder Phase Ihrer Unternehmungen. Sie ergreifen die Chancen. Wir verwandeln Risiken in L\u00f6sungen.\",\"publisher\":{\"@id\":\"https:\/\/www.chg.at\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.chg.at\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.chg.at\/en\/#organization\",\"name\":\"CHG Czernich Rechtsanw\u00e4lte\",\"url\":\"https:\/\/www.chg.at\/en\/\",\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/12773263\/admin\/dashboard\/\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.chg.at\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.chg.at\/wp-content\/uploads\/2016\/08\/CHG_logo_250_1.png\",\"contentUrl\":\"https:\/\/www.chg.at\/wp-content\/uploads\/2016\/08\/CHG_logo_250_1.png\",\"width\":250,\"height\":33,\"caption\":\"CHG Czernich Rechtsanw\u00e4lte\"},\"image\":{\"@id\":\"https:\/\/www.chg.at\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.chg.at\/en\/#\/schema\/person\/767a36d24c2ac329c1c5e1c10929e2b6\",\"name\":\"Lorenz Held\",\"sameAs\":[\"https:\/\/www.chg.at\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Covid-19 und Arbeitsrecht Home-Office \u2013 Regelungsbedarf und F\u00f6rderungsm\u00f6glichkeiten","description":"Arbeitsrechtliche COVID-19-Ma\u00dfnahmen: Home-Office \u2013 Regelungsbedarf und F\u00f6rderungsm\u00f6glichkeiten. RA Dr. Marlene Wachter, RAA Mag. Julia Barenth. 14.04.2020.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.chg.at\/en\/arbeitsrechtliche-covid-19-massnahmen-home-office\/","og_locale":"en_US","og_type":"article","og_title":"CHG","og_description":"CHG","og_url":"https:\/\/www.chg.at\/en\/arbeitsrechtliche-covid-19-massnahmen-home-office\/","og_site_name":"CHG Czernich Rechtsanw\u00e4lte \u2013 Wir bewegen Wirtschaft","article_published_time":"2020-04-15T08:37:22+00:00","article_modified_time":"2020-05-20T13:23:21+00:00","og_image":[{"width":1160,"height":580,"url":"https:\/\/www.chg.at\/wp-content\/uploads\/2020\/04\/Recht-und-Corona.png","type":"image\/png"}],"author":"Lorenz Held","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Lorenz Held","Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.chg.at\/en\/arbeitsrechtliche-covid-19-massnahmen-home-office\/#article","isPartOf":{"@id":"https:\/\/www.chg.at\/en\/arbeitsrechtliche-covid-19-massnahmen-home-office\/"},"author":{"name":"Lorenz Held","@id":"https:\/\/www.chg.at\/en\/#\/schema\/person\/767a36d24c2ac329c1c5e1c10929e2b6"},"headline":"Arbeitsrechtliche COVID-19-Ma\u00dfnahmen: Home-Office","datePublished":"2020-04-15T08:37:22+00:00","dateModified":"2020-05-20T13:23:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.chg.at\/en\/arbeitsrechtliche-covid-19-massnahmen-home-office\/"},"wordCount":1636,"publisher":{"@id":"https:\/\/www.chg.at\/en\/#organization"},"articleSection":["Business Tipps","CHG News","Publikation","Recht und Corona"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.chg.at\/en\/arbeitsrechtliche-covid-19-massnahmen-home-office\/","url":"https:\/\/www.chg.at\/en\/arbeitsrechtliche-covid-19-massnahmen-home-office\/","name":"Covid-19 und Arbeitsrecht Home-Office \u2013 Regelungsbedarf und F\u00f6rderungsm\u00f6glichkeiten","isPartOf":{"@id":"https:\/\/www.chg.at\/en\/#website"},"datePublished":"2020-04-15T08:37:22+00:00","dateModified":"2020-05-20T13:23:21+00:00","description":"Arbeitsrechtliche COVID-19-Ma\u00dfnahmen: Home-Office \u2013 Regelungsbedarf und F\u00f6rderungsm\u00f6glichkeiten. RA Dr. Marlene Wachter, RAA Mag. Julia Barenth. 14.04.2020.","breadcrumb":{"@id":"https:\/\/www.chg.at\/en\/arbeitsrechtliche-covid-19-massnahmen-home-office\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.chg.at\/en\/arbeitsrechtliche-covid-19-massnahmen-home-office\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.chg.at\/en\/arbeitsrechtliche-covid-19-massnahmen-home-office\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.chg.at\/en\/"},{"@type":"ListItem","position":2,"name":"Arbeitsrechtliche COVID-19-Ma\u00dfnahmen: Home-Office"}]},{"@type":"WebSite","@id":"https:\/\/www.chg.at\/en\/#website","url":"https:\/\/www.chg.at\/en\/","name":"CHG Czernich Rechtsanw\u00e4lte \u2013 Wir bewegen Wirtschaft","description":"Wir sorgen f\u00fcr Klarheit, wenn es rechtlich kompliziert wird. In jeder Phase Ihrer Unternehmungen. Sie ergreifen die Chancen. Wir verwandeln Risiken in L\u00f6sungen.","publisher":{"@id":"https:\/\/www.chg.at\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.chg.at\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.chg.at\/en\/#organization","name":"CHG Czernich Rechtsanw\u00e4lte","url":"https:\/\/www.chg.at\/en\/","sameAs":["https:\/\/www.linkedin.com\/company\/12773263\/admin\/dashboard\/"],"logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.chg.at\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.chg.at\/wp-content\/uploads\/2016\/08\/CHG_logo_250_1.png","contentUrl":"https:\/\/www.chg.at\/wp-content\/uploads\/2016\/08\/CHG_logo_250_1.png","width":250,"height":33,"caption":"CHG Czernich Rechtsanw\u00e4lte"},"image":{"@id":"https:\/\/www.chg.at\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.chg.at\/en\/#\/schema\/person\/767a36d24c2ac329c1c5e1c10929e2b6","name":"Lorenz Held","sameAs":["https:\/\/www.chg.at"]}]}},"_links":{"self":[{"href":"https:\/\/www.chg.at\/en\/wp-json\/wp\/v2\/posts\/12324"}],"collection":[{"href":"https:\/\/www.chg.at\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.chg.at\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.chg.at\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chg.at\/en\/wp-json\/wp\/v2\/comments?post=12324"}],"version-history":[{"count":10,"href":"https:\/\/www.chg.at\/en\/wp-json\/wp\/v2\/posts\/12324\/revisions"}],"predecessor-version":[{"id":12570,"href":"https:\/\/www.chg.at\/en\/wp-json\/wp\/v2\/posts\/12324\/revisions\/12570"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.chg.at\/en\/wp-json\/wp\/v2\/media\/12341"}],"wp:attachment":[{"href":"https:\/\/www.chg.at\/en\/wp-json\/wp\/v2\/media?parent=12324"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.chg.at\/en\/wp-json\/wp\/v2\/categories?post=12324"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.chg.at\/en\/wp-json\/wp\/v2\/tags?post=12324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}